{"id":169,"count":73,"description":"","link":"https:\/\/zxdoll.com\/it\/collections\/sex-doll-on-sale\/","name":"Sex Doll On Sale","slug":"sex-doll-on-sale","taxonomy":"product_cat","parent":0,"meta":[],"menu_order":0,"_links":{"self":[{"href":"https:\/\/zxdoll.com\/it\/wp-json\/wp\/v2\/product_cat\/169","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/zxdoll.com\/it\/wp-json\/wp\/v2\/product_cat"}],"about":[{"href":"https:\/\/zxdoll.com\/it\/wp-json\/wp\/v2\/taxonomies\/product_cat"}],"wp:post_type":[{"href":"https:\/\/zxdoll.com\/it\/wp-json\/wp\/v2\/product?product_cat=169"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}