{"id":117,"count":2388,"description":"","link":"https:\/\/zxdoll.com\/it\/collections\/small-breast-sex-doll\/","name":"Small Breast Sex Doll","slug":"small-breast-sex-doll","taxonomy":"product_cat","parent":0,"meta":[],"menu_order":0,"_links":{"self":[{"href":"https:\/\/zxdoll.com\/it\/wp-json\/wp\/v2\/product_cat\/117","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/zxdoll.com\/it\/wp-json\/wp\/v2\/product_cat"}],"about":[{"href":"https:\/\/zxdoll.com\/it\/wp-json\/wp\/v2\/taxonomies\/product_cat"}],"wp:post_type":[{"href":"https:\/\/zxdoll.com\/it\/wp-json\/wp\/v2\/product?product_cat=117"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}