{"id":22839,"date":"2023-03-12T03:47:12","date_gmt":"2023-03-11T19:47:12","guid":{"rendered":"https:\/\/zxdoll.com\/?post_type=product&#038;p=22839"},"modified":"2025-09-11T00:19:18","modified_gmt":"2025-09-10T16:19:18","slug":"full-size-lifelike-tpe-love-doll-for-sale","status":"publish","type":"product","link":"https:\/\/zxdoll.com\/it\/product\/full-size-lifelike-tpe-love-doll-for-sale\/","title":{"rendered":"Bambola d&#039;amore in TPE realistica a grandezza naturale in vendita Shenita 168 cm"},"content":{"rendered":"<h4><strong>Immagini di bambole del sesso<\/strong><\/h4>\n\t                <ul class=\"easy-image-gallery thumbnails-22 linked\">\r\n                    <li><a data-fancybox=\"gallery395\" href=\"https:\/\/zxdoll.com\/wp-content\/uploads\/2023\/03\/adult-dolls-for-sale-z8k1-800x800.jpg\" class=\"eig-popup\" title=\"\" data-caption=\"\" target=\"_blank\"><i class=\"icon-view\"><\/i><span class=\"overlay\"><\/span><img decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/zxdoll.com\/wp-content\/uploads\/2023\/03\/adult-dolls-for-sale-z8k1-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" srcset=\"https:\/\/zxdoll.com\/wp-content\/uploads\/2023\/03\/adult-dolls-for-sale-z8k1-150x150.jpg 150w, https:\/\/zxdoll.com\/wp-content\/uploads\/2023\/03\/adult-dolls-for-sale-z8k1-300x300.jpg 300w, https:\/\/zxdoll.com\/wp-content\/uploads\/2023\/03\/adult-dolls-for-sale-z8k1-800x800.jpg 800w, https:\/\/zxdoll.com\/wp-content\/uploads\/2023\/03\/adult-dolls-for-sale-z8k1-768x768.jpg 768w, https:\/\/zxdoll.com\/wp-content\/uploads\/2023\/03\/adult-dolls-for-sale-z8k1-12x12.jpg 12w, https:\/\/zxdoll.com\/wp-content\/uploads\/2023\/03\/adult-dolls-for-sale-z8k1-860x860.jpg 860w, https:\/\/zxdoll.com\/wp-content\/uploads\/2023\/03\/adult-dolls-for-sale-z8k1-430x430.jpg 430w, https:\/\/zxdoll.com\/wp-content\/uploads\/2023\/03\/adult-dolls-for-sale-z8k1-700x700.jpg 700w, https:\/\/zxdoll.com\/wp-content\/uploads\/2023\/03\/adult-dolls-for-sale-z8k1.jpg 1000w\" sizes=\"(max-width: 150px) 100vw, 150px\" title=\"\"><\/a><\/li><li><a data-fancybox=\"gallery395\" href=\"https:\/\/zxdoll.com\/wp-content\/uploads\/2023\/03\/adult-dolls-for-sale-z8k2-800x800.jpg\" class=\"eig-popup\" title=\"\" data-caption=\"\" target=\"_blank\"><i class=\"icon-view\"><\/i><span class=\"overlay\"><\/span><img decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/zxdoll.com\/wp-content\/uploads\/2023\/03\/adult-dolls-for-sale-z8k2-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" srcset=\"https:\/\/zxdoll.com\/wp-content\/uploads\/2023\/03\/adult-dolls-for-sale-z8k2-150x150.jpg 150w, https:\/\/zxdoll.com\/wp-content\/uploads\/2023\/03\/adult-dolls-for-sale-z8k2-300x300.jpg 300w, https:\/\/zxdoll.com\/wp-content\/uploads\/2023\/03\/adult-dolls-for-sale-z8k2-800x800.jpg 800w, https:\/\/zxdoll.com\/wp-content\/uploads\/2023\/03\/adult-dolls-for-sale-z8k2-768x768.jpg 768w, https:\/\/zxdoll.com\/wp-content\/uploads\/2023\/03\/adult-dolls-for-sale-z8k2-12x12.jpg 12w, https:\/\/zxdoll.com\/wp-content\/uploads\/2023\/03\/adult-dolls-for-sale-z8k2-860x860.jpg 860w, https:\/\/zxdoll.com\/wp-content\/uploads\/2023\/03\/adult-dolls-for-sale-z8k2-430x430.jpg 430w, https:\/\/zxdoll.com\/wp-content\/uploads\/2023\/03\/adult-dolls-for-sale-z8k2-700x700.jpg 700w, https:\/\/zxdoll.com\/wp-content\/uploads\/2023\/03\/adult-dolls-for-sale-z8k2.jpg 1000w\" sizes=\"(max-width: 150px) 100vw, 150px\" title=\"\"><\/a><\/li><li><a data-fancybox=\"gallery395\" href=\"https:\/\/zxdoll.com\/wp-content\/uploads\/2023\/03\/adult-dolls-for-sale-z8k3-800x800.jpg\" class=\"eig-popup\" title=\"\" data-caption=\"\" target=\"_blank\"><i class=\"icon-view\"><\/i><span class=\"overlay\"><\/span><img decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/zxdoll.com\/wp-content\/uploads\/2023\/03\/adult-dolls-for-sale-z8k3-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" srcset=\"https:\/\/zxdoll.com\/wp-content\/uploads\/2023\/03\/adult-dolls-for-sale-z8k3-150x150.jpg 150w, https:\/\/zxdoll.com\/wp-content\/uploads\/2023\/03\/adult-dolls-for-sale-z8k3-300x300.jpg 300w, https:\/\/zxdoll.com\/wp-content\/uploads\/2023\/03\/adult-dolls-for-sale-z8k3-800x800.jpg 800w, https:\/\/zxdoll.com\/wp-content\/uploads\/2023\/03\/adult-dolls-for-sale-z8k3-768x768.jpg 768w, https:\/\/zxdoll.com\/wp-content\/uploads\/2023\/03\/adult-dolls-for-sale-z8k3-12x12.jpg 12w, https:\/\/zxdoll.com\/wp-content\/uploads\/2023\/03\/adult-dolls-for-sale-z8k3-860x860.jpg 860w, https:\/\/zxdoll.com\/wp-content\/uploads\/2023\/03\/adult-dolls-for-sale-z8k3-430x430.jpg 430w, https:\/\/zxdoll.com\/wp-content\/uploads\/2023\/03\/adult-dolls-for-sale-z8k3-700x700.jpg 700w, https:\/\/zxdoll.com\/wp-content\/uploads\/2023\/03\/adult-dolls-for-sale-z8k3.jpg 1000w\" sizes=\"(max-width: 150px) 100vw, 150px\" title=\"\"><\/a><\/li><li><a data-fancybox=\"gallery395\" href=\"https:\/\/zxdoll.com\/wp-content\/uploads\/2023\/03\/adult-dolls-for-sale-z8k4-1-800x800.jpg\" class=\"eig-popup\" title=\"\" data-caption=\"\" target=\"_blank\"><i class=\"icon-view\"><\/i><span class=\"overlay\"><\/span><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/zxdoll.com\/wp-content\/uploads\/2023\/03\/adult-dolls-for-sale-z8k4-1-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" srcset=\"https:\/\/zxdoll.com\/wp-content\/uploads\/2023\/03\/adult-dolls-for-sale-z8k4-1-150x150.jpg 150w, https:\/\/zxdoll.com\/wp-content\/uploads\/2023\/03\/adult-dolls-for-sale-z8k4-1-300x300.jpg 300w, https:\/\/zxdoll.com\/wp-content\/uploads\/2023\/03\/adult-dolls-for-sale-z8k4-1-800x800.jpg 800w, https:\/\/zxdoll.com\/wp-content\/uploads\/2023\/03\/adult-dolls-for-sale-z8k4-1-768x768.jpg 768w, https:\/\/zxdoll.com\/wp-content\/uploads\/2023\/03\/adult-dolls-for-sale-z8k4-1-12x12.jpg 12w, https:\/\/zxdoll.com\/wp-content\/uploads\/2023\/03\/adult-dolls-for-sale-z8k4-1-860x860.jpg 860w, https:\/\/zxdoll.com\/wp-content\/uploads\/2023\/03\/adult-dolls-for-sale-z8k4-1-430x430.jpg 430w, https:\/\/zxdoll.com\/wp-content\/uploads\/2023\/03\/adult-dolls-for-sale-z8k4-1-700x700.jpg 700w, https:\/\/zxdoll.com\/wp-content\/uploads\/2023\/03\/adult-dolls-for-sale-z8k4-1.jpg 1000w\" sizes=\"(max-width: 150px) 100vw, 150px\" title=\"\"><\/a><\/li><li><a data-fancybox=\"gallery395\" href=\"https:\/\/zxdoll.com\/wp-content\/uploads\/2023\/03\/adult-dolls-for-sale-z8k5-800x800.jpg\" class=\"eig-popup\" title=\"\" data-caption=\"\" target=\"_blank\"><i class=\"icon-view\"><\/i><span class=\"overlay\"><\/span><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/zxdoll.com\/wp-content\/uploads\/2023\/03\/adult-dolls-for-sale-z8k5-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" srcset=\"https:\/\/zxdoll.com\/wp-content\/uploads\/2023\/03\/adult-dolls-for-sale-z8k5-150x150.jpg 150w, https:\/\/zxdoll.com\/wp-content\/uploads\/2023\/03\/adult-dolls-for-sale-z8k5-300x300.jpg 300w, https:\/\/zxdoll.com\/wp-content\/uploads\/2023\/03\/adult-dolls-for-sale-z8k5-800x800.jpg 800w, https:\/\/zxdoll.com\/wp-content\/uploads\/2023\/03\/adult-dolls-for-sale-z8k5-768x768.jpg 768w, https:\/\/zxdoll.com\/wp-content\/uploads\/2023\/03\/adult-dolls-for-sale-z8k5-12x12.jpg 12w, https:\/\/zxdoll.com\/wp-content\/uploads\/2023\/03\/adult-dolls-for-sale-z8k5-860x860.jpg 860w, https:\/\/zxdoll.com\/wp-content\/uploads\/2023\/03\/adult-dolls-for-sale-z8k5-430x430.jpg 430w, https:\/\/zxdoll.com\/wp-content\/uploads\/2023\/03\/adult-dolls-for-sale-z8k5-700x700.jpg 700w, https:\/\/zxdoll.com\/wp-content\/uploads\/2023\/03\/adult-dolls-for-sale-z8k5.jpg 1000w\" sizes=\"(max-width: 150px) 100vw, 150px\" title=\"\"><\/a><\/li><li><a data-fancybox=\"gallery395\" href=\"https:\/\/zxdoll.com\/wp-content\/uploads\/2023\/03\/adult-dolls-for-sale-z8k6-800x800.jpg\" class=\"eig-popup\" title=\"\" data-caption=\"\" target=\"_blank\"><i class=\"icon-view\"><\/i><span class=\"overlay\"><\/span><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/zxdoll.com\/wp-content\/uploads\/2023\/03\/adult-dolls-for-sale-z8k6-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" srcset=\"https:\/\/zxdoll.com\/wp-content\/uploads\/2023\/03\/adult-dolls-for-sale-z8k6-150x150.jpg 150w, https:\/\/zxdoll.com\/wp-content\/uploads\/2023\/03\/adult-dolls-for-sale-z8k6-300x300.jpg 300w, https:\/\/zxdoll.com\/wp-content\/uploads\/2023\/03\/adult-dolls-for-sale-z8k6-800x800.jpg 800w, https:\/\/zxdoll.com\/wp-content\/uploads\/2023\/03\/adult-dolls-for-sale-z8k6-768x768.jpg 768w, https:\/\/zxdoll.com\/wp-content\/uploads\/2023\/03\/adult-dolls-for-sale-z8k6-12x12.jpg 12w, https:\/\/zxdoll.com\/wp-content\/uploads\/2023\/03\/adult-dolls-for-sale-z8k6-860x860.jpg 860w, https:\/\/zxdoll.com\/wp-content\/uploads\/2023\/03\/adult-dolls-for-sale-z8k6-430x430.jpg 430w, https:\/\/zxdoll.com\/wp-content\/uploads\/2023\/03\/adult-dolls-for-sale-z8k6-700x700.jpg 700w, https:\/\/zxdoll.com\/wp-content\/uploads\/2023\/03\/adult-dolls-for-sale-z8k6.jpg 1000w\" sizes=\"(max-width: 150px) 100vw, 150px\" title=\"\"><\/a><\/li><li><a data-fancybox=\"gallery395\" href=\"https:\/\/zxdoll.com\/wp-content\/uploads\/2023\/03\/adult-dolls-for-sale-z8k7-800x800.jpg\" class=\"eig-popup\" title=\"\" data-caption=\"\" target=\"_blank\"><i class=\"icon-view\"><\/i><span class=\"overlay\"><\/span><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/zxdoll.com\/wp-content\/uploads\/2023\/03\/adult-dolls-for-sale-z8k7-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" srcset=\"https:\/\/zxdoll.com\/wp-content\/uploads\/2023\/03\/adult-dolls-for-sale-z8k7-150x150.jpg 150w, https:\/\/zxdoll.com\/wp-content\/uploads\/2023\/03\/adult-dolls-for-sale-z8k7-300x300.jpg 300w, https:\/\/zxdoll.com\/wp-content\/uploads\/2023\/03\/adult-dolls-for-sale-z8k7-800x800.jpg 800w, https:\/\/zxdoll.com\/wp-content\/uploads\/2023\/03\/adult-dolls-for-sale-z8k7-768x768.jpg 768w, https:\/\/zxdoll.com\/wp-content\/uploads\/2023\/03\/adult-dolls-for-sale-z8k7-12x12.jpg 12w, https:\/\/zxdoll.com\/wp-content\/uploads\/2023\/03\/adult-dolls-for-sale-z8k7-860x860.jpg 860w, https:\/\/zxdoll.com\/wp-content\/uploads\/2023\/03\/adult-dolls-for-sale-z8k7-430x430.jpg 430w, https:\/\/zxdoll.com\/wp-content\/uploads\/2023\/03\/adult-dolls-for-sale-z8k7-700x700.jpg 700w, https:\/\/zxdoll.com\/wp-content\/uploads\/2023\/03\/adult-dolls-for-sale-z8k7.jpg 1000w\" sizes=\"(max-width: 150px) 100vw, 150px\" title=\"\"><\/a><\/li><li><a data-fancybox=\"gallery395\" href=\"https:\/\/zxdoll.com\/wp-content\/uploads\/2023\/03\/adult-dolls-for-sale-z8k8-800x800.jpg\" class=\"eig-popup\" title=\"\" data-caption=\"\" target=\"_blank\"><i class=\"icon-view\"><\/i><span class=\"overlay\"><\/span><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/zxdoll.com\/wp-content\/uploads\/2023\/03\/adult-dolls-for-sale-z8k8-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" srcset=\"https:\/\/zxdoll.com\/wp-content\/uploads\/2023\/03\/adult-dolls-for-sale-z8k8-150x150.jpg 150w, https:\/\/zxdoll.com\/wp-content\/uploads\/2023\/03\/adult-dolls-for-sale-z8k8-300x300.jpg 300w, https:\/\/zxdoll.com\/wp-content\/uploads\/2023\/03\/adult-dolls-for-sale-z8k8-800x800.jpg 800w, https:\/\/zxdoll.com\/wp-content\/uploads\/2023\/03\/adult-dolls-for-sale-z8k8-768x768.jpg 768w, https:\/\/zxdoll.com\/wp-content\/uploads\/2023\/03\/adult-dolls-for-sale-z8k8-12x12.jpg 12w, https:\/\/zxdoll.com\/wp-content\/uploads\/2023\/03\/adult-dolls-for-sale-z8k8-860x860.jpg 860w, https:\/\/zxdoll.com\/wp-content\/uploads\/2023\/03\/adult-dolls-for-sale-z8k8-430x430.jpg 430w, https:\/\/zxdoll.com\/wp-content\/uploads\/2023\/03\/adult-dolls-for-sale-z8k8-700x700.jpg 700w, https:\/\/zxdoll.com\/wp-content\/uploads\/2023\/03\/adult-dolls-for-sale-z8k8.jpg 1000w\" sizes=\"(max-width: 150px) 100vw, 150px\" title=\"\"><\/a><\/li><li><a data-fancybox=\"gallery395\" href=\"https:\/\/zxdoll.com\/wp-content\/uploads\/2023\/03\/adult-dolls-for-sale-z8k12-800x800.jpg\" class=\"eig-popup\" title=\"\" data-caption=\"\" target=\"_blank\"><i class=\"icon-view\"><\/i><span class=\"overlay\"><\/span><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/zxdoll.com\/wp-content\/uploads\/2023\/03\/adult-dolls-for-sale-z8k12-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" srcset=\"https:\/\/zxdoll.com\/wp-content\/uploads\/2023\/03\/adult-dolls-for-sale-z8k12-150x150.jpg 150w, https:\/\/zxdoll.com\/wp-content\/uploads\/2023\/03\/adult-dolls-for-sale-z8k12-300x300.jpg 300w, https:\/\/zxdoll.com\/wp-content\/uploads\/2023\/03\/adult-dolls-for-sale-z8k12-800x800.jpg 800w, https:\/\/zxdoll.com\/wp-content\/uploads\/2023\/03\/adult-dolls-for-sale-z8k12-768x768.jpg 768w, https:\/\/zxdoll.com\/wp-content\/uploads\/2023\/03\/adult-dolls-for-sale-z8k12-12x12.jpg 12w, https:\/\/zxdoll.com\/wp-content\/uploads\/2023\/03\/adult-dolls-for-sale-z8k12-860x860.jpg 860w, https:\/\/zxdoll.com\/wp-content\/uploads\/2023\/03\/adult-dolls-for-sale-z8k12-430x430.jpg 430w, https:\/\/zxdoll.com\/wp-content\/uploads\/2023\/03\/adult-dolls-for-sale-z8k12-700x700.jpg 700w, https:\/\/zxdoll.com\/wp-content\/uploads\/2023\/03\/adult-dolls-for-sale-z8k12.jpg 1000w\" sizes=\"(max-width: 150px) 100vw, 150px\" title=\"\"><\/a><\/li><li><a data-fancybox=\"gallery395\" href=\"https:\/\/zxdoll.com\/wp-content\/uploads\/2023\/03\/adult-dolls-for-sale-z8k14-800x800.jpg\" class=\"eig-popup\" title=\"\" data-caption=\"\" target=\"_blank\"><i class=\"icon-view\"><\/i><span class=\"overlay\"><\/span><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/zxdoll.com\/wp-content\/uploads\/2023\/03\/adult-dolls-for-sale-z8k14-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" srcset=\"https:\/\/zxdoll.com\/wp-content\/uploads\/2023\/03\/adult-dolls-for-sale-z8k14-150x150.jpg 150w, https:\/\/zxdoll.com\/wp-content\/uploads\/2023\/03\/adult-dolls-for-sale-z8k14-300x300.jpg 300w, https:\/\/zxdoll.com\/wp-content\/uploads\/2023\/03\/adult-dolls-for-sale-z8k14-800x800.jpg 800w, https:\/\/zxdoll.com\/wp-content\/uploads\/2023\/03\/adult-dolls-for-sale-z8k14-768x768.jpg 768w, https:\/\/zxdoll.com\/wp-content\/uploads\/2023\/03\/adult-dolls-for-sale-z8k14-12x12.jpg 12w, https:\/\/zxdoll.com\/wp-content\/uploads\/2023\/03\/adult-dolls-for-sale-z8k14-860x860.jpg 860w, https:\/\/zxdoll.com\/wp-content\/uploads\/2023\/03\/adult-dolls-for-sale-z8k14-430x430.jpg 430w, https:\/\/zxdoll.com\/wp-content\/uploads\/2023\/03\/adult-dolls-for-sale-z8k14-700x700.jpg 700w, https:\/\/zxdoll.com\/wp-content\/uploads\/2023\/03\/adult-dolls-for-sale-z8k14.jpg 1000w\" sizes=\"(max-width: 150px) 100vw, 150px\" title=\"\"><\/a><\/li><li><a data-fancybox=\"gallery395\" href=\"https:\/\/zxdoll.com\/wp-content\/uploads\/2023\/03\/adult-dolls-for-sale-z8k15-800x800.jpg\" class=\"eig-popup\" title=\"\" data-caption=\"\" target=\"_blank\"><i class=\"icon-view\"><\/i><span class=\"overlay\"><\/span><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/zxdoll.com\/wp-content\/uploads\/2023\/03\/adult-dolls-for-sale-z8k15-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" srcset=\"https:\/\/zxdoll.com\/wp-content\/uploads\/2023\/03\/adult-dolls-for-sale-z8k15-150x150.jpg 150w, https:\/\/zxdoll.com\/wp-content\/uploads\/2023\/03\/adult-dolls-for-sale-z8k15-300x300.jpg 300w, https:\/\/zxdoll.com\/wp-content\/uploads\/2023\/03\/adult-dolls-for-sale-z8k15-800x800.jpg 800w, https:\/\/zxdoll.com\/wp-content\/uploads\/2023\/03\/adult-dolls-for-sale-z8k15-768x768.jpg 768w, https:\/\/zxdoll.com\/wp-content\/uploads\/2023\/03\/adult-dolls-for-sale-z8k15-12x12.jpg 12w, https:\/\/zxdoll.com\/wp-content\/uploads\/2023\/03\/adult-dolls-for-sale-z8k15-860x860.jpg 860w, https:\/\/zxdoll.com\/wp-content\/uploads\/2023\/03\/adult-dolls-for-sale-z8k15-430x430.jpg 430w, https:\/\/zxdoll.com\/wp-content\/uploads\/2023\/03\/adult-dolls-for-sale-z8k15-700x700.jpg 700w, https:\/\/zxdoll.com\/wp-content\/uploads\/2023\/03\/adult-dolls-for-sale-z8k15.jpg 1000w\" sizes=\"(max-width: 150px) 100vw, 150px\" title=\"\"><\/a><\/li><li><a data-fancybox=\"gallery395\" href=\"https:\/\/zxdoll.com\/wp-content\/uploads\/2023\/03\/adult-dolls-for-sale-z8k16-800x800.jpg\" class=\"eig-popup\" title=\"\" data-caption=\"\" target=\"_blank\"><i class=\"icon-view\"><\/i><span class=\"overlay\"><\/span><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/zxdoll.com\/wp-content\/uploads\/2023\/03\/adult-dolls-for-sale-z8k16-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" srcset=\"https:\/\/zxdoll.com\/wp-content\/uploads\/2023\/03\/adult-dolls-for-sale-z8k16-150x150.jpg 150w, https:\/\/zxdoll.com\/wp-content\/uploads\/2023\/03\/adult-dolls-for-sale-z8k16-300x300.jpg 300w, https:\/\/zxdoll.com\/wp-content\/uploads\/2023\/03\/adult-dolls-for-sale-z8k16-800x800.jpg 800w, https:\/\/zxdoll.com\/wp-content\/uploads\/2023\/03\/adult-dolls-for-sale-z8k16-768x768.jpg 768w, https:\/\/zxdoll.com\/wp-content\/uploads\/2023\/03\/adult-dolls-for-sale-z8k16-12x12.jpg 12w, https:\/\/zxdoll.com\/wp-content\/uploads\/2023\/03\/adult-dolls-for-sale-z8k16-860x860.jpg 860w, https:\/\/zxdoll.com\/wp-content\/uploads\/2023\/03\/adult-dolls-for-sale-z8k16-430x430.jpg 430w, https:\/\/zxdoll.com\/wp-content\/uploads\/2023\/03\/adult-dolls-for-sale-z8k16-700x700.jpg 700w, https:\/\/zxdoll.com\/wp-content\/uploads\/2023\/03\/adult-dolls-for-sale-z8k16.jpg 1000w\" sizes=\"(max-width: 150px) 100vw, 150px\" title=\"\"><\/a><\/li><li><a data-fancybox=\"gallery395\" href=\"https:\/\/zxdoll.com\/wp-content\/uploads\/2023\/03\/adult-dolls-for-sale-z8k19-800x800.jpg\" class=\"eig-popup\" title=\"\" data-caption=\"\" target=\"_blank\"><i class=\"icon-view\"><\/i><span class=\"overlay\"><\/span><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/zxdoll.com\/wp-content\/uploads\/2023\/03\/adult-dolls-for-sale-z8k19-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" srcset=\"https:\/\/zxdoll.com\/wp-content\/uploads\/2023\/03\/adult-dolls-for-sale-z8k19-150x150.jpg 150w, https:\/\/zxdoll.com\/wp-content\/uploads\/2023\/03\/adult-dolls-for-sale-z8k19-300x300.jpg 300w, https:\/\/zxdoll.com\/wp-content\/uploads\/2023\/03\/adult-dolls-for-sale-z8k19-800x800.jpg 800w, https:\/\/zxdoll.com\/wp-content\/uploads\/2023\/03\/adult-dolls-for-sale-z8k19-768x768.jpg 768w, https:\/\/zxdoll.com\/wp-content\/uploads\/2023\/03\/adult-dolls-for-sale-z8k19-12x12.jpg 12w, https:\/\/zxdoll.com\/wp-content\/uploads\/2023\/03\/adult-dolls-for-sale-z8k19-860x860.jpg 860w, https:\/\/zxdoll.com\/wp-content\/uploads\/2023\/03\/adult-dolls-for-sale-z8k19-430x430.jpg 430w, https:\/\/zxdoll.com\/wp-content\/uploads\/2023\/03\/adult-dolls-for-sale-z8k19-700x700.jpg 700w, https:\/\/zxdoll.com\/wp-content\/uploads\/2023\/03\/adult-dolls-for-sale-z8k19.jpg 1000w\" sizes=\"(max-width: 150px) 100vw, 150px\" title=\"\"><\/a><\/li><li><a data-fancybox=\"gallery395\" href=\"https:\/\/zxdoll.com\/wp-content\/uploads\/2023\/03\/adult-dolls-for-sale-z8k20-1.jpg\" class=\"eig-popup\" title=\"\" data-caption=\"\" target=\"_blank\"><i class=\"icon-view\"><\/i><span class=\"overlay\"><\/span><img loading=\"lazy\" decoding=\"async\" width=\"100\" height=\"150\" src=\"https:\/\/zxdoll.com\/wp-content\/uploads\/2023\/03\/adult-dolls-for-sale-z8k20-1.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" title=\"\"><\/a><\/li><li><a data-fancybox=\"gallery395\" href=\"https:\/\/zxdoll.com\/wp-content\/uploads\/2023\/03\/adult-dolls-for-sale-z8k22-800x800.jpg\" class=\"eig-popup\" title=\"\" data-caption=\"\" target=\"_blank\"><i class=\"icon-view\"><\/i><span class=\"overlay\"><\/span><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/zxdoll.com\/wp-content\/uploads\/2023\/03\/adult-dolls-for-sale-z8k22-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" srcset=\"https:\/\/zxdoll.com\/wp-content\/uploads\/2023\/03\/adult-dolls-for-sale-z8k22-150x150.jpg 150w, https:\/\/zxdoll.com\/wp-content\/uploads\/2023\/03\/adult-dolls-for-sale-z8k22-300x300.jpg 300w, https:\/\/zxdoll.com\/wp-content\/uploads\/2023\/03\/adult-dolls-for-sale-z8k22-800x800.jpg 800w, https:\/\/zxdoll.com\/wp-content\/uploads\/2023\/03\/adult-dolls-for-sale-z8k22-768x768.jpg 768w, https:\/\/zxdoll.com\/wp-content\/uploads\/2023\/03\/adult-dolls-for-sale-z8k22-12x12.jpg 12w, https:\/\/zxdoll.com\/wp-content\/uploads\/2023\/03\/adult-dolls-for-sale-z8k22-860x860.jpg 860w, https:\/\/zxdoll.com\/wp-content\/uploads\/2023\/03\/adult-dolls-for-sale-z8k22-430x430.jpg 430w, https:\/\/zxdoll.com\/wp-content\/uploads\/2023\/03\/adult-dolls-for-sale-z8k22-700x700.jpg 700w, https:\/\/zxdoll.com\/wp-content\/uploads\/2023\/03\/adult-dolls-for-sale-z8k22.jpg 1000w\" sizes=\"(max-width: 150px) 100vw, 150px\" title=\"\"><\/a><\/li><li><a data-fancybox=\"gallery395\" href=\"https:\/\/zxdoll.com\/wp-content\/uploads\/2023\/03\/adult-dolls-for-sale-z8k23-800x800.jpg\" class=\"eig-popup\" title=\"\" data-caption=\"\" target=\"_blank\"><i class=\"icon-view\"><\/i><span class=\"overlay\"><\/span><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/zxdoll.com\/wp-content\/uploads\/2023\/03\/adult-dolls-for-sale-z8k23-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" srcset=\"https:\/\/zxdoll.com\/wp-content\/uploads\/2023\/03\/adult-dolls-for-sale-z8k23-150x150.jpg 150w, https:\/\/zxdoll.com\/wp-content\/uploads\/2023\/03\/adult-dolls-for-sale-z8k23-300x300.jpg 300w, https:\/\/zxdoll.com\/wp-content\/uploads\/2023\/03\/adult-dolls-for-sale-z8k23-800x800.jpg 800w, https:\/\/zxdoll.com\/wp-content\/uploads\/2023\/03\/adult-dolls-for-sale-z8k23-768x768.jpg 768w, https:\/\/zxdoll.com\/wp-content\/uploads\/2023\/03\/adult-dolls-for-sale-z8k23-12x12.jpg 12w, https:\/\/zxdoll.com\/wp-content\/uploads\/2023\/03\/adult-dolls-for-sale-z8k23-860x860.jpg 860w, https:\/\/zxdoll.com\/wp-content\/uploads\/2023\/03\/adult-dolls-for-sale-z8k23-430x430.jpg 430w, https:\/\/zxdoll.com\/wp-content\/uploads\/2023\/03\/adult-dolls-for-sale-z8k23-700x700.jpg 700w, https:\/\/zxdoll.com\/wp-content\/uploads\/2023\/03\/adult-dolls-for-sale-z8k23.jpg 1000w\" sizes=\"(max-width: 150px) 100vw, 150px\" title=\"\"><\/a><\/li><li><a data-fancybox=\"gallery395\" href=\"https:\/\/zxdoll.com\/wp-content\/uploads\/2023\/03\/adult-dolls-for-sale-z8k24-800x800.jpg\" class=\"eig-popup\" title=\"\" data-caption=\"\" target=\"_blank\"><i class=\"icon-view\"><\/i><span class=\"overlay\"><\/span><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/zxdoll.com\/wp-content\/uploads\/2023\/03\/adult-dolls-for-sale-z8k24-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" srcset=\"https:\/\/zxdoll.com\/wp-content\/uploads\/2023\/03\/adult-dolls-for-sale-z8k24-150x150.jpg 150w, https:\/\/zxdoll.com\/wp-content\/uploads\/2023\/03\/adult-dolls-for-sale-z8k24-300x300.jpg 300w, https:\/\/zxdoll.com\/wp-content\/uploads\/2023\/03\/adult-dolls-for-sale-z8k24-800x800.jpg 800w, https:\/\/zxdoll.com\/wp-content\/uploads\/2023\/03\/adult-dolls-for-sale-z8k24-768x768.jpg 768w, https:\/\/zxdoll.com\/wp-content\/uploads\/2023\/03\/adult-dolls-for-sale-z8k24-12x12.jpg 12w, https:\/\/zxdoll.com\/wp-content\/uploads\/2023\/03\/adult-dolls-for-sale-z8k24-860x860.jpg 860w, https:\/\/zxdoll.com\/wp-content\/uploads\/2023\/03\/adult-dolls-for-sale-z8k24-430x430.jpg 430w, https:\/\/zxdoll.com\/wp-content\/uploads\/2023\/03\/adult-dolls-for-sale-z8k24-700x700.jpg 700w, https:\/\/zxdoll.com\/wp-content\/uploads\/2023\/03\/adult-dolls-for-sale-z8k24.jpg 1000w\" sizes=\"(max-width: 150px) 100vw, 150px\" title=\"\"><\/a><\/li><li><a data-fancybox=\"gallery395\" href=\"https:\/\/zxdoll.com\/wp-content\/uploads\/2023\/03\/adult-dolls-for-sale-z8k25-800x800.jpg\" class=\"eig-popup\" title=\"\" data-caption=\"\" target=\"_blank\"><i class=\"icon-view\"><\/i><span class=\"overlay\"><\/span><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/zxdoll.com\/wp-content\/uploads\/2023\/03\/adult-dolls-for-sale-z8k25-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" srcset=\"https:\/\/zxdoll.com\/wp-content\/uploads\/2023\/03\/adult-dolls-for-sale-z8k25-150x150.jpg 150w, https:\/\/zxdoll.com\/wp-content\/uploads\/2023\/03\/adult-dolls-for-sale-z8k25-300x300.jpg 300w, https:\/\/zxdoll.com\/wp-content\/uploads\/2023\/03\/adult-dolls-for-sale-z8k25-800x800.jpg 800w, https:\/\/zxdoll.com\/wp-content\/uploads\/2023\/03\/adult-dolls-for-sale-z8k25-768x768.jpg 768w, https:\/\/zxdoll.com\/wp-content\/uploads\/2023\/03\/adult-dolls-for-sale-z8k25-12x12.jpg 12w, https:\/\/zxdoll.com\/wp-content\/uploads\/2023\/03\/adult-dolls-for-sale-z8k25-860x860.jpg 860w, https:\/\/zxdoll.com\/wp-content\/uploads\/2023\/03\/adult-dolls-for-sale-z8k25-430x430.jpg 430w, https:\/\/zxdoll.com\/wp-content\/uploads\/2023\/03\/adult-dolls-for-sale-z8k25-700x700.jpg 700w, https:\/\/zxdoll.com\/wp-content\/uploads\/2023\/03\/adult-dolls-for-sale-z8k25.jpg 1000w\" sizes=\"(max-width: 150px) 100vw, 150px\" title=\"\"><\/a><\/li><li><a data-fancybox=\"gallery395\" href=\"https:\/\/zxdoll.com\/wp-content\/uploads\/2023\/03\/adult-dolls-for-sale-z8k27-800x800.jpg\" class=\"eig-popup\" title=\"\" data-caption=\"\" target=\"_blank\"><i class=\"icon-view\"><\/i><span class=\"overlay\"><\/span><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/zxdoll.com\/wp-content\/uploads\/2023\/03\/adult-dolls-for-sale-z8k27-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" srcset=\"https:\/\/zxdoll.com\/wp-content\/uploads\/2023\/03\/adult-dolls-for-sale-z8k27-150x150.jpg 150w, https:\/\/zxdoll.com\/wp-content\/uploads\/2023\/03\/adult-dolls-for-sale-z8k27-300x300.jpg 300w, https:\/\/zxdoll.com\/wp-content\/uploads\/2023\/03\/adult-dolls-for-sale-z8k27-800x800.jpg 800w, https:\/\/zxdoll.com\/wp-content\/uploads\/2023\/03\/adult-dolls-for-sale-z8k27-768x768.jpg 768w, https:\/\/zxdoll.com\/wp-content\/uploads\/2023\/03\/adult-dolls-for-sale-z8k27-12x12.jpg 12w, https:\/\/zxdoll.com\/wp-content\/uploads\/2023\/03\/adult-dolls-for-sale-z8k27-860x860.jpg 860w, https:\/\/zxdoll.com\/wp-content\/uploads\/2023\/03\/adult-dolls-for-sale-z8k27-430x430.jpg 430w, https:\/\/zxdoll.com\/wp-content\/uploads\/2023\/03\/adult-dolls-for-sale-z8k27-700x700.jpg 700w, https:\/\/zxdoll.com\/wp-content\/uploads\/2023\/03\/adult-dolls-for-sale-z8k27.jpg 1000w\" sizes=\"(max-width: 150px) 100vw, 150px\" title=\"\"><\/a><\/li><li><a data-fancybox=\"gallery395\" href=\"https:\/\/zxdoll.com\/wp-content\/uploads\/2023\/03\/adult-dolls-for-sale-z8k28-800x800.jpg\" class=\"eig-popup\" title=\"\" data-caption=\"\" target=\"_blank\"><i class=\"icon-view\"><\/i><span class=\"overlay\"><\/span><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/zxdoll.com\/wp-content\/uploads\/2023\/03\/adult-dolls-for-sale-z8k28-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" srcset=\"https:\/\/zxdoll.com\/wp-content\/uploads\/2023\/03\/adult-dolls-for-sale-z8k28-150x150.jpg 150w, https:\/\/zxdoll.com\/wp-content\/uploads\/2023\/03\/adult-dolls-for-sale-z8k28-300x300.jpg 300w, https:\/\/zxdoll.com\/wp-content\/uploads\/2023\/03\/adult-dolls-for-sale-z8k28-800x800.jpg 800w, https:\/\/zxdoll.com\/wp-content\/uploads\/2023\/03\/adult-dolls-for-sale-z8k28-768x768.jpg 768w, https:\/\/zxdoll.com\/wp-content\/uploads\/2023\/03\/adult-dolls-for-sale-z8k28-12x12.jpg 12w, https:\/\/zxdoll.com\/wp-content\/uploads\/2023\/03\/adult-dolls-for-sale-z8k28-860x860.jpg 860w, https:\/\/zxdoll.com\/wp-content\/uploads\/2023\/03\/adult-dolls-for-sale-z8k28-430x430.jpg 430w, https:\/\/zxdoll.com\/wp-content\/uploads\/2023\/03\/adult-dolls-for-sale-z8k28-700x700.jpg 700w, https:\/\/zxdoll.com\/wp-content\/uploads\/2023\/03\/adult-dolls-for-sale-z8k28.jpg 1000w\" sizes=\"(max-width: 150px) 100vw, 150px\" title=\"\"><\/a><\/li><li><a data-fancybox=\"gallery395\" href=\"https:\/\/zxdoll.com\/wp-content\/uploads\/2023\/03\/adult-dolls-for-sale-z8k29-800x800.jpg\" class=\"eig-popup\" title=\"\" data-caption=\"\" target=\"_blank\"><i class=\"icon-view\"><\/i><span class=\"overlay\"><\/span><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/zxdoll.com\/wp-content\/uploads\/2023\/03\/adult-dolls-for-sale-z8k29-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" srcset=\"https:\/\/zxdoll.com\/wp-content\/uploads\/2023\/03\/adult-dolls-for-sale-z8k29-150x150.jpg 150w, https:\/\/zxdoll.com\/wp-content\/uploads\/2023\/03\/adult-dolls-for-sale-z8k29-300x300.jpg 300w, https:\/\/zxdoll.com\/wp-content\/uploads\/2023\/03\/adult-dolls-for-sale-z8k29-800x800.jpg 800w, https:\/\/zxdoll.com\/wp-content\/uploads\/2023\/03\/adult-dolls-for-sale-z8k29-768x768.jpg 768w, https:\/\/zxdoll.com\/wp-content\/uploads\/2023\/03\/adult-dolls-for-sale-z8k29-12x12.jpg 12w, https:\/\/zxdoll.com\/wp-content\/uploads\/2023\/03\/adult-dolls-for-sale-z8k29-860x860.jpg 860w, https:\/\/zxdoll.com\/wp-content\/uploads\/2023\/03\/adult-dolls-for-sale-z8k29-430x430.jpg 430w, https:\/\/zxdoll.com\/wp-content\/uploads\/2023\/03\/adult-dolls-for-sale-z8k29-700x700.jpg 700w, https:\/\/zxdoll.com\/wp-content\/uploads\/2023\/03\/adult-dolls-for-sale-z8k29.jpg 1000w\" sizes=\"(max-width: 150px) 100vw, 150px\" title=\"\"><\/a><\/li><li><a data-fancybox=\"gallery395\" href=\"https:\/\/zxdoll.com\/wp-content\/uploads\/2023\/03\/adult-dolls-for-sale-z8k30-800x800.jpg\" class=\"eig-popup\" title=\"\" data-caption=\"\" target=\"_blank\"><i class=\"icon-view\"><\/i><span class=\"overlay\"><\/span><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/zxdoll.com\/wp-content\/uploads\/2023\/03\/adult-dolls-for-sale-z8k30-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" srcset=\"https:\/\/zxdoll.com\/wp-content\/uploads\/2023\/03\/adult-dolls-for-sale-z8k30-150x150.jpg 150w, https:\/\/zxdoll.com\/wp-content\/uploads\/2023\/03\/adult-dolls-for-sale-z8k30-300x300.jpg 300w, https:\/\/zxdoll.com\/wp-content\/uploads\/2023\/03\/adult-dolls-for-sale-z8k30-800x800.jpg 800w, https:\/\/zxdoll.com\/wp-content\/uploads\/2023\/03\/adult-dolls-for-sale-z8k30-768x768.jpg 768w, https:\/\/zxdoll.com\/wp-content\/uploads\/2023\/03\/adult-dolls-for-sale-z8k30-12x12.jpg 12w, https:\/\/zxdoll.com\/wp-content\/uploads\/2023\/03\/adult-dolls-for-sale-z8k30-860x860.jpg 860w, https:\/\/zxdoll.com\/wp-content\/uploads\/2023\/03\/adult-dolls-for-sale-z8k30-430x430.jpg 430w, https:\/\/zxdoll.com\/wp-content\/uploads\/2023\/03\/adult-dolls-for-sale-z8k30-700x700.jpg 700w, https:\/\/zxdoll.com\/wp-content\/uploads\/2023\/03\/adult-dolls-for-sale-z8k30.jpg 1000w\" sizes=\"(max-width: 150px) 100vw, 150px\" title=\"\"><\/a><\/li><\/ul>\n<h4>Tabelle delle taglie<\/h4>\n<table width=\"269\">\n<tbody>\n<tr>\n<td width=\"130\">Materiale<\/td>\n<td width=\"139\">TPE<\/td>\n<\/tr>\n<tr>\n<td>Altezza<\/td>\n<td>168 cm<\/td>\n<\/tr>\n<tr>\n<td>Seno<\/td>\n<td>79 cm<\/td>\n<\/tr>\n<tr>\n<td>Vita<\/td>\n<td>59 cm<\/td>\n<\/tr>\n<tr>\n<td>Anca<\/td>\n<td>87 cm<\/td>\n<\/tr>\n<tr>\n<td>Spalla<\/td>\n<td>37cm<\/td>\n<\/tr>\n<tr>\n<td>Lunghezza della gamba<\/td>\n<td>86 cm<\/td>\n<\/tr>\n<tr>\n<td>Lunghezza del braccio<\/td>\n<td>60 cm<\/td>\n<\/tr>\n<tr>\n<td>Lunghezza del piede<\/td>\n<td>20 cm<\/td>\n<\/tr>\n<tr>\n<td>Peso netto<\/td>\n<td>39 kg<\/td>\n<\/tr>\n<tr>\n<td>Profondit\u00e0 orale<\/td>\n<td>12 cm<\/td>\n<\/tr>\n<tr>\n<td>Profondit\u00e0 vaginale<\/td>\n<td>22 cm<\/td>\n<\/tr>\n<tr>\n<td>Profondit\u00e0 anale<\/td>\n<td>18 cm<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<h4>Informazioni sulla bambola del sesso<\/h4>\n<p>Nessun&#039;altra bambola d&#039;amore carina pu\u00f2 soddisfare i tuoi desideri pi\u00f9 dolci e sexy come queste bambole d&#039;amore tpe in vendita. Con tette meravigliosamente modellate e sicuramente le fighe pi\u00f9 strette e divertenti sul mercato delle bambole del sesso, queste bambole in tpe sono le migliori per una scopata potente e soddisfacente. Anche se la bambola del sesso pi\u00f9 simile alla vita, non c&#039;\u00e8 quasi nessuna sensazione paragonabile a ci\u00f2 che pu\u00f2 offrire questa bambola dell&#039;amore da 168 cm.<\/p>\n<p>Non c&#039;\u00e8 niente di meglio o di pi\u00f9 desiderabile di tali bambole dell&#039;amore realistiche, completamente flessibili, flessibili e disponibili. Varie fantastiche posizioni sessuali sono molto pi\u00f9 facili da ottenere con questo amante speciale di dimensioni divertenti per te. Creata appositamente per la tua gioia, dimostra di essere l&#039;ultima ragazza a dare un trattamento speciale con un bel cazzo mentre guardi le espressioni innocenti e dolci sul suo viso. La sua sensazione morbida e invitante \u00e8 destinata a farti provare ogni trucco del libro sul suo culo.<\/p>\n<p>Una volta che inizi con questa realistica bambola dell&#039;amore, non vorrai pi\u00f9 fermarti. Questa damigella \u00e8 fatta appositamente per veri uomini alfa che amano essere al comando e farle godere la sensazione di un vero cazzo dentro di lei.<\/p>","protected":false},"excerpt":{"rendered":"<p>Immagini della bambola del sesso Tabelle delle taglie Materiale TPE Altezza 168 cm Seno 79 cm Vita 59 cm Anca 87 cm Spalla 37 cm Lunghezza gamba 86 cm<\/p>","protected":false},"featured_media":22854,"comment_status":"open","ping_status":"closed","template":"","meta":[],"product_brand":[],"product_cat":[75,230,100,107,117,119],"product_tag":[],"class_list":{"0":"post-22839","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-160cm-170cm-sex-dolls","7":"product_cat-36kg-40kg","8":"product_cat-lifelike-love-dolls","9":"product_cat-skinny-sex-dolls","10":"product_cat-small-breast-sex-doll","11":"product_cat-tpe-sex-doll","12":"pa_brand-hr-doll","13":"tm-has-options","15":"first","16":"instock","17":"sale","18":"shipping-taxable","19":"purchasable","20":"product-type-simple"},"_links":{"self":[{"href":"https:\/\/zxdoll.com\/it\/wp-json\/wp\/v2\/product\/22839","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/zxdoll.com\/it\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/zxdoll.com\/it\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/zxdoll.com\/it\/wp-json\/wp\/v2\/comments?post=22839"}],"version-history":[{"count":1,"href":"https:\/\/zxdoll.com\/it\/wp-json\/wp\/v2\/product\/22839\/revisions"}],"predecessor-version":[{"id":197741,"href":"https:\/\/zxdoll.com\/it\/wp-json\/wp\/v2\/product\/22839\/revisions\/197741"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/zxdoll.com\/it\/wp-json\/wp\/v2\/media\/22854"}],"wp:attachment":[{"href":"https:\/\/zxdoll.com\/it\/wp-json\/wp\/v2\/media?parent=22839"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/zxdoll.com\/it\/wp-json\/wp\/v2\/product_brand?post=22839"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/zxdoll.com\/it\/wp-json\/wp\/v2\/product_cat?post=22839"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/zxdoll.com\/it\/wp-json\/wp\/v2\/product_tag?post=22839"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}