{"id":125455,"date":"2023-07-28T02:46:47","date_gmt":"2023-07-27T18:46:47","guid":{"rendered":"https:\/\/zxdoll.com\/?post_type=product&#038;p=125455"},"modified":"2025-09-14T23:44:32","modified_gmt":"2025-09-14T15:44:32","slug":"tip-sex-doll-bikini-cup-boobs","status":"publish","type":"product","link":"https:\/\/zxdoll.com\/it\/product\/tip-sex-doll-bikini-cup-boobs\/","title":{"rendered":"Tip Sex Doll Bikini Cup Boobs Tillie 170cm"},"content":{"rendered":"<h4><strong>Immagini di bambole del sesso<\/strong><\/h4>\n\t                <ul class=\"easy-image-gallery thumbnails-22 linked\">\r\n                    <li><a data-fancybox=\"gallery370\" href=\"https:\/\/zxdoll.com\/wp-content\/uploads\/2023\/07\/using-sex-doll-shax1-533x800.jpg\" class=\"eig-popup\" title=\"\" data-caption=\"\" target=\"_blank\"><i class=\"icon-view\"><\/i><span class=\"overlay\"><\/span><img decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/zxdoll.com\/wp-content\/uploads\/2023\/07\/using-sex-doll-shax1-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" title=\"\"><\/a><\/li><li><a data-fancybox=\"gallery370\" href=\"https:\/\/zxdoll.com\/wp-content\/uploads\/2023\/07\/using-sex-doll-shax2-533x800.jpg\" class=\"eig-popup\" title=\"\" data-caption=\"\" target=\"_blank\"><i class=\"icon-view\"><\/i><span class=\"overlay\"><\/span><img decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/zxdoll.com\/wp-content\/uploads\/2023\/07\/using-sex-doll-shax2-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" title=\"\"><\/a><\/li><li><a data-fancybox=\"gallery370\" href=\"https:\/\/zxdoll.com\/wp-content\/uploads\/2023\/07\/using-sex-doll-shax6-533x800.jpg\" class=\"eig-popup\" title=\"\" data-caption=\"\" target=\"_blank\"><i class=\"icon-view\"><\/i><span class=\"overlay\"><\/span><img decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/zxdoll.com\/wp-content\/uploads\/2023\/07\/using-sex-doll-shax6-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" title=\"\"><\/a><\/li><li><a data-fancybox=\"gallery370\" href=\"https:\/\/zxdoll.com\/wp-content\/uploads\/2023\/07\/using-sex-doll-shax8-533x800.jpg\" class=\"eig-popup\" title=\"\" data-caption=\"\" target=\"_blank\"><i class=\"icon-view\"><\/i><span class=\"overlay\"><\/span><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/zxdoll.com\/wp-content\/uploads\/2023\/07\/using-sex-doll-shax8-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" title=\"\"><\/a><\/li><li><a data-fancybox=\"gallery370\" href=\"https:\/\/zxdoll.com\/wp-content\/uploads\/2023\/07\/using-sex-doll-shax9-533x800.jpg\" class=\"eig-popup\" title=\"\" data-caption=\"\" target=\"_blank\"><i class=\"icon-view\"><\/i><span class=\"overlay\"><\/span><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/zxdoll.com\/wp-content\/uploads\/2023\/07\/using-sex-doll-shax9-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" title=\"\"><\/a><\/li><li><a data-fancybox=\"gallery370\" href=\"https:\/\/zxdoll.com\/wp-content\/uploads\/2023\/07\/using-sex-doll-shax14-533x800.jpg\" class=\"eig-popup\" title=\"\" data-caption=\"\" target=\"_blank\"><i class=\"icon-view\"><\/i><span class=\"overlay\"><\/span><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/zxdoll.com\/wp-content\/uploads\/2023\/07\/using-sex-doll-shax14-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" title=\"\"><\/a><\/li><li><a data-fancybox=\"gallery370\" href=\"https:\/\/zxdoll.com\/wp-content\/uploads\/2023\/07\/using-sex-doll-shax15-533x800.jpg\" class=\"eig-popup\" title=\"\" data-caption=\"\" target=\"_blank\"><i class=\"icon-view\"><\/i><span class=\"overlay\"><\/span><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/zxdoll.com\/wp-content\/uploads\/2023\/07\/using-sex-doll-shax15-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" title=\"\"><\/a><\/li><li><a data-fancybox=\"gallery370\" href=\"https:\/\/zxdoll.com\/wp-content\/uploads\/2023\/07\/using-sex-doll-shax17-533x800.jpg\" class=\"eig-popup\" title=\"\" data-caption=\"\" target=\"_blank\"><i class=\"icon-view\"><\/i><span class=\"overlay\"><\/span><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/zxdoll.com\/wp-content\/uploads\/2023\/07\/using-sex-doll-shax17-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" title=\"\"><\/a><\/li><li><a data-fancybox=\"gallery370\" href=\"https:\/\/zxdoll.com\/wp-content\/uploads\/2023\/07\/using-sex-doll-shax19-533x800.jpg\" class=\"eig-popup\" title=\"\" data-caption=\"\" target=\"_blank\"><i class=\"icon-view\"><\/i><span class=\"overlay\"><\/span><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/zxdoll.com\/wp-content\/uploads\/2023\/07\/using-sex-doll-shax19-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" title=\"\"><\/a><\/li><li><a data-fancybox=\"gallery370\" href=\"https:\/\/zxdoll.com\/wp-content\/uploads\/2023\/07\/using-sex-doll-shax20-533x800.jpg\" class=\"eig-popup\" title=\"\" data-caption=\"\" target=\"_blank\"><i class=\"icon-view\"><\/i><span class=\"overlay\"><\/span><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/zxdoll.com\/wp-content\/uploads\/2023\/07\/using-sex-doll-shax20-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" title=\"\"><\/a><\/li><li><a data-fancybox=\"gallery370\" href=\"https:\/\/zxdoll.com\/wp-content\/uploads\/2023\/07\/using-sex-doll-shax21.jpg\" class=\"eig-popup\" title=\"\" data-caption=\"\" target=\"_blank\"><i class=\"icon-view\"><\/i><span class=\"overlay\"><\/span><img loading=\"lazy\" decoding=\"async\" width=\"100\" height=\"150\" src=\"https:\/\/zxdoll.com\/wp-content\/uploads\/2023\/07\/using-sex-doll-shax21.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" title=\"\"><\/a><\/li><li><a data-fancybox=\"gallery370\" href=\"https:\/\/zxdoll.com\/wp-content\/uploads\/2023\/07\/using-sex-doll-shax22.jpg\" class=\"eig-popup\" title=\"\" data-caption=\"\" target=\"_blank\"><i class=\"icon-view\"><\/i><span class=\"overlay\"><\/span><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/zxdoll.com\/wp-content\/uploads\/2023\/07\/using-sex-doll-shax22-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" title=\"\"><\/a><\/li><li><a data-fancybox=\"gallery370\" href=\"https:\/\/zxdoll.com\/wp-content\/uploads\/2023\/07\/using-sex-doll-shax24-533x800.jpg\" class=\"eig-popup\" title=\"\" data-caption=\"\" target=\"_blank\"><i class=\"icon-view\"><\/i><span class=\"overlay\"><\/span><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/zxdoll.com\/wp-content\/uploads\/2023\/07\/using-sex-doll-shax24-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" title=\"\"><\/a><\/li><li><a data-fancybox=\"gallery370\" href=\"https:\/\/zxdoll.com\/wp-content\/uploads\/2023\/07\/using-sex-doll-shax25-533x800.jpg\" class=\"eig-popup\" title=\"\" data-caption=\"\" target=\"_blank\"><i class=\"icon-view\"><\/i><span class=\"overlay\"><\/span><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/zxdoll.com\/wp-content\/uploads\/2023\/07\/using-sex-doll-shax25-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" title=\"\"><\/a><\/li><li><a data-fancybox=\"gallery370\" href=\"https:\/\/zxdoll.com\/wp-content\/uploads\/2023\/07\/using-sex-doll-shax26-533x800.jpg\" class=\"eig-popup\" title=\"\" data-caption=\"\" target=\"_blank\"><i class=\"icon-view\"><\/i><span class=\"overlay\"><\/span><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/zxdoll.com\/wp-content\/uploads\/2023\/07\/using-sex-doll-shax26-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" title=\"\"><\/a><\/li><li><a data-fancybox=\"gallery370\" href=\"https:\/\/zxdoll.com\/wp-content\/uploads\/2023\/07\/using-sex-doll-shax27.jpg\" class=\"eig-popup\" title=\"\" data-caption=\"\" target=\"_blank\"><i class=\"icon-view\"><\/i><span class=\"overlay\"><\/span><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/zxdoll.com\/wp-content\/uploads\/2023\/07\/using-sex-doll-shax27-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" title=\"\"><\/a><\/li><li><a data-fancybox=\"gallery370\" href=\"https:\/\/zxdoll.com\/wp-content\/uploads\/2023\/07\/using-sex-doll-shax28-533x800.jpg\" class=\"eig-popup\" title=\"\" data-caption=\"\" target=\"_blank\"><i class=\"icon-view\"><\/i><span class=\"overlay\"><\/span><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/zxdoll.com\/wp-content\/uploads\/2023\/07\/using-sex-doll-shax28-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" title=\"\"><\/a><\/li><li><a data-fancybox=\"gallery370\" href=\"https:\/\/zxdoll.com\/wp-content\/uploads\/2023\/07\/using-sex-doll-shax30-533x800.jpg\" class=\"eig-popup\" title=\"\" data-caption=\"\" target=\"_blank\"><i class=\"icon-view\"><\/i><span class=\"overlay\"><\/span><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/zxdoll.com\/wp-content\/uploads\/2023\/07\/using-sex-doll-shax30-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" title=\"\"><\/a><\/li><li><a data-fancybox=\"gallery370\" href=\"https:\/\/zxdoll.com\/wp-content\/uploads\/2023\/07\/using-sex-doll-shax31.jpg\" class=\"eig-popup\" title=\"\" data-caption=\"\" target=\"_blank\"><i class=\"icon-view\"><\/i><span class=\"overlay\"><\/span><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/zxdoll.com\/wp-content\/uploads\/2023\/07\/using-sex-doll-shax31-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" title=\"\"><\/a><\/li><li><a data-fancybox=\"gallery370\" href=\"https:\/\/zxdoll.com\/wp-content\/uploads\/2023\/07\/using-sex-doll-shax32.jpg\" class=\"eig-popup\" title=\"\" data-caption=\"\" target=\"_blank\"><i class=\"icon-view\"><\/i><span class=\"overlay\"><\/span><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/zxdoll.com\/wp-content\/uploads\/2023\/07\/using-sex-doll-shax32-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" title=\"\"><\/a><\/li><li><a data-fancybox=\"gallery370\" href=\"https:\/\/zxdoll.com\/wp-content\/uploads\/2023\/07\/using-sex-doll-shax33-533x800.jpg\" class=\"eig-popup\" title=\"\" data-caption=\"\" target=\"_blank\"><i class=\"icon-view\"><\/i><span class=\"overlay\"><\/span><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/zxdoll.com\/wp-content\/uploads\/2023\/07\/using-sex-doll-shax33-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" title=\"\"><\/a><\/li><li><a data-fancybox=\"gallery370\" href=\"https:\/\/zxdoll.com\/wp-content\/uploads\/2023\/07\/using-sex-doll-shax34.jpg\" class=\"eig-popup\" title=\"\" data-caption=\"\" target=\"_blank\"><i class=\"icon-view\"><\/i><span class=\"overlay\"><\/span><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/zxdoll.com\/wp-content\/uploads\/2023\/07\/using-sex-doll-shax34-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" title=\"\"><\/a><\/li><\/ul>\n<h4>Tabelle delle taglie<\/h4>\n<table width=\"269\">\n<tbody>\n<tr>\n<td width=\"130\">Materiale<\/td>\n<td width=\"139\">TPE<\/td>\n<\/tr>\n<tr>\n<td>Altezza<\/td>\n<td>170 cm<\/td>\n<\/tr>\n<tr>\n<td>Seno<\/td>\n<td>80 cm<\/td>\n<\/tr>\n<tr>\n<td>Vita<\/td>\n<td>68 cm<\/td>\n<\/tr>\n<tr>\n<td>Anca<\/td>\n<td>90 cm<\/td>\n<\/tr>\n<tr>\n<td>Larghezza delle spalle<\/td>\n<td>36 cm<\/td>\n<\/tr>\n<tr>\n<td>Lunghezza del braccio<\/td>\n<td>50cm<\/td>\n<\/tr>\n<tr>\n<td>Lunghezza della mano<\/td>\n<td>15cm<\/td>\n<\/tr>\n<tr>\n<td>Lunghezza della gamba<\/td>\n<td>80 cm<\/td>\n<\/tr>\n<tr>\n<td>Linea della coscia<\/td>\n<td>52 cm<\/td>\n<\/tr>\n<tr>\n<td>Linea Vitello<\/td>\n<td>33 cm<\/td>\n<\/tr>\n<tr>\n<td>Dimensione dei piedi<\/td>\n<td>21 cm<\/td>\n<\/tr>\n<tr>\n<td>Profondit\u00e0 orale<\/td>\n<td>10 cm<\/td>\n<\/tr>\n<tr>\n<td>Profondit\u00e0 della vagina<\/td>\n<td>14 cm<\/td>\n<\/tr>\n<tr>\n<td>Profondit\u00e0 anale<\/td>\n<td>10 cm<\/td>\n<\/tr>\n<tr>\n<td>Peso netto<\/td>\n<td>42 kg<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<h4>Informazioni sulla bambola del sesso<\/h4>\n<p>&nbsp;<\/p>","protected":false},"excerpt":{"rendered":"<p>Immagini della bambola del sesso Tabelle delle taglie Materiale TPE Altezza 170 cm Seno 80 cm Vita 68 cm Anca 90 cm Larghezza spalla 36 cm Lunghezza braccio<\/p>","protected":false},"featured_media":125509,"comment_status":"open","ping_status":"closed","template":"","meta":[],"product_brand":[],"product_cat":[165,75,231,107,117,119],"product_tag":[],"class_list":{"0":"post-125455","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-fine-love-dolls","7":"product_cat-160cm-170cm-sex-dolls","8":"product_cat-41kg-45kg","9":"product_cat-skinny-sex-dolls","10":"product_cat-small-breast-sex-doll","11":"product_cat-tpe-sex-doll","12":"pa_brand-qita-doll","13":"tm-has-options","15":"first","16":"instock","17":"sale","18":"shipping-taxable","19":"purchasable","20":"product-type-simple"},"_links":{"self":[{"href":"https:\/\/zxdoll.com\/it\/wp-json\/wp\/v2\/product\/125455","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/zxdoll.com\/it\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/zxdoll.com\/it\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/zxdoll.com\/it\/wp-json\/wp\/v2\/comments?post=125455"}],"version-history":[{"count":1,"href":"https:\/\/zxdoll.com\/it\/wp-json\/wp\/v2\/product\/125455\/revisions"}],"predecessor-version":[{"id":125532,"href":"https:\/\/zxdoll.com\/it\/wp-json\/wp\/v2\/product\/125455\/revisions\/125532"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/zxdoll.com\/it\/wp-json\/wp\/v2\/media\/125509"}],"wp:attachment":[{"href":"https:\/\/zxdoll.com\/it\/wp-json\/wp\/v2\/media?parent=125455"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/zxdoll.com\/it\/wp-json\/wp\/v2\/product_brand?post=125455"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/zxdoll.com\/it\/wp-json\/wp\/v2\/product_cat?post=125455"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/zxdoll.com\/it\/wp-json\/wp\/v2\/product_tag?post=125455"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}