{"id":177967,"date":"2024-09-22T02:50:04","date_gmt":"2024-09-21T18:50:04","guid":{"rendered":"https:\/\/zxdoll.com\/?post_type=product&#038;p=177967"},"modified":"2024-10-02T00:24:35","modified_gmt":"2024-10-01T16:24:35","slug":"full-body-transgender-sex-doll","status":"publish","type":"product","link":"https:\/\/zxdoll.com\/hu\/product\/full-body-transgender-sex-doll\/","title":{"rendered":"Teljes test\u0171 transznem\u0171 szexbaba Pippy 168 cm"},"content":{"rendered":"<h4><strong>Szexbaba k\u00e9pek<\/strong><\/h4>\n\t                <ul class=\"easy-image-gallery thumbnails-8 linked\">\r\n                    <li><a data-fancybox=\"gallery587\" href=\"https:\/\/zxdoll.com\/wp-content\/uploads\/2024\/09\/aeris-sex-doll-qJr02d2-Copy-533x800.jpg\" class=\"eig-popup\" title=\"\" data-caption=\"\" target=\"_blank\"><i class=\"icon-view\"><\/i><span class=\"overlay\"><\/span><img decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/zxdoll.com\/wp-content\/uploads\/2024\/09\/aeris-sex-doll-qJr02d2-Copy-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" title=\"\"><\/a><\/li><li><a data-fancybox=\"gallery587\" href=\"https:\/\/zxdoll.com\/wp-content\/uploads\/2024\/09\/aeris-sex-doll-qJr02d3-Copy-533x800.jpg\" class=\"eig-popup\" title=\"\" data-caption=\"\" target=\"_blank\"><i class=\"icon-view\"><\/i><span class=\"overlay\"><\/span><img decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/zxdoll.com\/wp-content\/uploads\/2024\/09\/aeris-sex-doll-qJr02d3-Copy-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" title=\"\"><\/a><\/li><li><a data-fancybox=\"gallery587\" href=\"https:\/\/zxdoll.com\/wp-content\/uploads\/2024\/09\/aeris-sex-doll-qJr02d4-Copy-533x800.jpg\" class=\"eig-popup\" title=\"\" data-caption=\"\" target=\"_blank\"><i class=\"icon-view\"><\/i><span class=\"overlay\"><\/span><img decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/zxdoll.com\/wp-content\/uploads\/2024\/09\/aeris-sex-doll-qJr02d4-Copy-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" title=\"\"><\/a><\/li><li><a data-fancybox=\"gallery587\" href=\"https:\/\/zxdoll.com\/wp-content\/uploads\/2024\/09\/aeris-sex-doll-qJr02d5-Copy-533x800.jpg\" class=\"eig-popup\" title=\"\" data-caption=\"\" target=\"_blank\"><i class=\"icon-view\"><\/i><span class=\"overlay\"><\/span><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/zxdoll.com\/wp-content\/uploads\/2024\/09\/aeris-sex-doll-qJr02d5-Copy-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" title=\"\"><\/a><\/li><li><a data-fancybox=\"gallery587\" href=\"https:\/\/zxdoll.com\/wp-content\/uploads\/2024\/09\/aeris-sex-doll-qJr02d6-Copy-533x800.jpg\" class=\"eig-popup\" title=\"\" data-caption=\"\" target=\"_blank\"><i class=\"icon-view\"><\/i><span class=\"overlay\"><\/span><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/zxdoll.com\/wp-content\/uploads\/2024\/09\/aeris-sex-doll-qJr02d6-Copy-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" title=\"\"><\/a><\/li><li><a data-fancybox=\"gallery587\" href=\"https:\/\/zxdoll.com\/wp-content\/uploads\/2024\/09\/aeris-sex-doll-qJr02d7-Copy-533x800.jpg\" class=\"eig-popup\" title=\"\" data-caption=\"\" target=\"_blank\"><i class=\"icon-view\"><\/i><span class=\"overlay\"><\/span><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/zxdoll.com\/wp-content\/uploads\/2024\/09\/aeris-sex-doll-qJr02d7-Copy-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" title=\"\"><\/a><\/li><li><a data-fancybox=\"gallery587\" href=\"https:\/\/zxdoll.com\/wp-content\/uploads\/2024\/09\/aeris-sex-doll-qJr02d8-Copy-533x800.jpg\" class=\"eig-popup\" title=\"\" data-caption=\"\" target=\"_blank\"><i class=\"icon-view\"><\/i><span class=\"overlay\"><\/span><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/zxdoll.com\/wp-content\/uploads\/2024\/09\/aeris-sex-doll-qJr02d8-Copy-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" title=\"\"><\/a><\/li><li><a data-fancybox=\"gallery587\" href=\"https:\/\/zxdoll.com\/wp-content\/uploads\/2024\/09\/aeris-sex-doll-qJr02d16-Copy-533x800.jpg\" class=\"eig-popup\" title=\"\" data-caption=\"\" target=\"_blank\"><i class=\"icon-view\"><\/i><span class=\"overlay\"><\/span><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/zxdoll.com\/wp-content\/uploads\/2024\/09\/aeris-sex-doll-qJr02d16-Copy-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" title=\"\"><\/a><\/li><\/ul>\n<h4>M\u00e9rett\u00e1bl\u00e1zatok<\/h4>\n<table width=\"256\">\n<tbody>\n<tr>\n<td width=\"129\">Anyag<\/td>\n<td width=\"127\">Teljes szilikon<\/td>\n<\/tr>\n<tr>\n<td>Magass\u00e1g<\/td>\n<td>168 cm<\/td>\n<\/tr>\n<tr>\n<td>Fels\u0151 mellkas<\/td>\n<td>89 cm<\/td>\n<\/tr>\n<tr>\n<td>Als\u00f3 mellkas<\/td>\n<td>62 cm<\/td>\n<\/tr>\n<tr>\n<td>Der\u00e9k<\/td>\n<td>56 cm<\/td>\n<\/tr>\n<tr>\n<td>Cs\u00edp\u0151<\/td>\n<td>86 cm<\/td>\n<\/tr>\n<tr>\n<td>V\u00e1ll<\/td>\n<td>33 cm<\/td>\n<\/tr>\n<tr>\n<td>Kar<\/td>\n<td>68 cm<\/td>\n<\/tr>\n<tr>\n<td>L\u00e1b<\/td>\n<td>87 cm<\/td>\n<\/tr>\n<tr>\n<td width=\"129\">L\u00e1b<\/td>\n<td>22 cm<\/td>\n<\/tr>\n<tr>\n<td width=\"129\">Nett\u00f3 t\u00f6meg<\/td>\n<td>40 kg<\/td>\n<\/tr>\n<tr>\n<td>H\u00fcvelym\u00e9lys\u00e9g<\/td>\n<td>18 cm<\/td>\n<\/tr>\n<tr>\n<td>An\u00e1lis m\u00e9lys\u00e9g<\/td>\n<td>15 cm<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<h4>A szexbab\u00e1r\u00f3l<\/h4>\n<p>&nbsp;<\/p>","protected":false},"excerpt":{"rendered":"<p>Szexbaba k\u00e9pek M\u00e9rett\u00e1bl\u00e1zat Anyag teljes szilikon magass\u00e1g 168 cm mellkas fels\u0151 89 cm mellkas als\u00f3 62 cm der\u00e9k 56 cm cs\u00edp\u0151 86 cm<\/p>","protected":false},"featured_media":178007,"comment_status":"open","ping_status":"closed","template":"","meta":[],"product_brand":[],"product_cat":[234,75,230,80,116,219,110,107],"product_tag":[],"class_list":["post-177967","product","type-product","status-publish","has-post-thumbnail","product_cat-234","product_cat-160cm-170cm-sex-dolls","product_cat-36kg-40kg","product_cat-asian-sex-doll","product_cat-big-boobs-sex-doll","product_cat-sex-doll-xxx","product_cat-silicone-sex-doll","product_cat-skinny-sex-dolls","pa_brand-doll-castle","tm-has-options","first","instock","sale","shipping-taxable","purchasable","product-type-simple"],"_links":{"self":[{"href":"https:\/\/zxdoll.com\/hu\/wp-json\/wp\/v2\/product\/177967","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/zxdoll.com\/hu\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/zxdoll.com\/hu\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/zxdoll.com\/hu\/wp-json\/wp\/v2\/comments?post=177967"}],"version-history":[{"count":2,"href":"https:\/\/zxdoll.com\/hu\/wp-json\/wp\/v2\/product\/177967\/revisions"}],"predecessor-version":[{"id":178023,"href":"https:\/\/zxdoll.com\/hu\/wp-json\/wp\/v2\/product\/177967\/revisions\/178023"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/zxdoll.com\/hu\/wp-json\/wp\/v2\/media\/178007"}],"wp:attachment":[{"href":"https:\/\/zxdoll.com\/hu\/wp-json\/wp\/v2\/media?parent=177967"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/zxdoll.com\/hu\/wp-json\/wp\/v2\/product_brand?post=177967"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/zxdoll.com\/hu\/wp-json\/wp\/v2\/product_cat?post=177967"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/zxdoll.com\/hu\/wp-json\/wp\/v2\/product_tag?post=177967"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}