{"id":218,"count":27,"description":"","link":"https:\/\/zxdoll.com\/fi\/collections\/wonder-woman-sex-doll\/","name":"Wonder Woman Sex Doll","slug":"wonder-woman-sex-doll","taxonomy":"product_cat","parent":0,"meta":[],"menu_order":0,"_links":{"self":[{"href":"https:\/\/zxdoll.com\/fi\/wp-json\/wp\/v2\/product_cat\/218","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/zxdoll.com\/fi\/wp-json\/wp\/v2\/product_cat"}],"about":[{"href":"https:\/\/zxdoll.com\/fi\/wp-json\/wp\/v2\/taxonomies\/product_cat"}],"wp:post_type":[{"href":"https:\/\/zxdoll.com\/fi\/wp-json\/wp\/v2\/product?product_cat=218"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}