{"id":119,"count":3001,"description":"","link":"https:\/\/zxdoll.com\/fi\/collections\/tpe-sex-doll\/","name":"TPE Sex Doll","slug":"tpe-sex-doll","taxonomy":"product_cat","parent":0,"meta":[],"menu_order":0,"_links":{"self":[{"href":"https:\/\/zxdoll.com\/fi\/wp-json\/wp\/v2\/product_cat\/119","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/zxdoll.com\/fi\/wp-json\/wp\/v2\/product_cat"}],"about":[{"href":"https:\/\/zxdoll.com\/fi\/wp-json\/wp\/v2\/taxonomies\/product_cat"}],"wp:post_type":[{"href":"https:\/\/zxdoll.com\/fi\/wp-json\/wp\/v2\/product?product_cat=119"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}